{"id":5750,"date":"2023-03-17T12:15:35","date_gmt":"2023-03-17T11:15:35","guid":{"rendered":"https:\/\/dayfor.com\/proyecto\/hopital-universitaire-de-toledo\/"},"modified":"2024-01-24T17:56:39","modified_gmt":"2024-01-24T16:56:39","slug":"hopital-universitaire-de-toledo","status":"publish","type":"proyecto","link":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/","title":{"rendered":"H\u00f4pital universitaire de Toledo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5750\" class=\"elementor elementor-5750 elementor-1531\" data-elementor-post-type=\"proyecto\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d531ec elementor-section-height-min-height elementor-section-full_width elementor-section-items-stretch elementor-section-height-default\" data-id=\"44d531ec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b8ae00c\" data-id=\"6b8ae00c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc5a1dd elementor-widget elementor-widget-breadcrumbs\" data-id=\"fc5a1dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/dayfor.com\/fr\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51fc23e5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"51fc23e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00f4pital universitaire de Toledo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-258d95f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"258d95f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e89c853\" data-id=\"4e89c853\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a469959 elementor-widget elementor-widget-heading\" data-id=\"5a469959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00f4pital universitaire de Toledo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-221b106a elementor-widget elementor-widget-text-editor\" data-id=\"221b106a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\"><span style=\"font-size: 12.0pt; line-height: 107%;\">L&rsquo;HUT compte plus de 5 000 portes fabriqu\u00e9es par Dayfor. Cet h\u00f4pital est le plus grand d&rsquo;Europe et le plus grand ouvrage civil de Castilla-La Mancha. Il se distingue par sa valeur architecturale et sa fonctionnalit\u00e9 en tant que centre hospitalier de grande capacit\u00e9. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50d605b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50d605b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fa98c3d\" data-id=\"fa98c3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19753e3 elementor-widget elementor-widget-heading\" data-id=\"19753e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Localisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-147d069d elementor-widget elementor-widget-text-editor\" data-id=\"147d069d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toledo, Espagne<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-31286b7a\" data-id=\"31286b7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d353cd6 elementor-widget elementor-widget-heading\" data-id=\"6d353cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a5c2794 elementor-widget elementor-widget-text-editor\" data-id=\"4a5c2794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: Calibri, sans-serif; font-size: 12pt; color: var( --e-global-color-text );\">Portes acoustiques 30dB faites en polystyr\u00e8ne avec un cadre en aluminium<\/span><b style=\"font-family: Calibri, sans-serif; font-size: 12pt; color: var( --e-global-color-text );\">,<\/b> <span style=\"font-family: Calibri, sans-serif; font-size: 12pt; color: var( --e-global-color-text );\">portes en <br \/>polystyr\u00e8ne avec cadre en aluminium, portes plomb\u00e9es, portes coulissantes <br \/>plomb\u00e9es.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-696adb2\" data-id=\"696adb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12b1a126 elementor-widget elementor-widget-heading\" data-id=\"12b1a126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Finition<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f33c87 elementor-widget elementor-widget-text-editor\" data-id=\"25f33c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>HPL<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d832b57\" data-id=\"d832b57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a828a2d elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"2a828a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2142\" height=\"2160\" src=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1.jpg\" class=\"attachment-full size-full wp-image-4759\" alt=\"\" srcset=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1.jpg 2142w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-298x300.jpg 298w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-1015x1024.jpg 1015w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-150x150.jpg 150w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-768x774.jpg 768w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-1523x1536.jpg 1523w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191113_110911_1-2031x2048.jpg 2031w\" sizes=\"(max-width: 2142px) 100vw, 2142px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c273524 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2c273524\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ddc8f3d\" data-id=\"1ddc8f3d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89866bc elementor-widget elementor-widget-image\" data-id=\"89866bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1108\" height=\"1200\" src=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada1.jpg\" class=\"attachment-full size-full wp-image-4771\" alt=\"\" srcset=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada1.jpg 1108w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada1-277x300.jpg 277w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada1-945x1024.jpg 945w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada1-768x832.jpg 768w\" sizes=\"(max-width: 1108px) 100vw, 1108px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da0e094\" data-id=\"da0e094\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07a3e06 elementor-widget elementor-widget-image\" data-id=\"07a3e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1108\" height=\"1200\" src=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191007_121600_1.jpg\" class=\"attachment-full size-full wp-image-4765\" alt=\"\" srcset=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191007_121600_1.jpg 1108w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191007_121600_1-277x300.jpg 277w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191007_121600_1-945x1024.jpg 945w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/20191007_121600_1-768x832.jpg 768w\" sizes=\"(max-width: 1108px) 100vw, 1108px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c66f979\" data-id=\"2c66f979\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a147762 elementor-widget elementor-widget-image\" data-id=\"6a147762\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1108\" height=\"1200\" src=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada2.jpg\" class=\"attachment-full size-full wp-image-4773\" alt=\"\" srcset=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada2.jpg 1108w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada2-277x300.jpg 277w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada2-945x1024.jpg 945w, https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/modificada2-768x832.jpg 768w\" sizes=\"(max-width: 1108px) 100vw, 1108px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25ca9170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25ca9170\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d20d953\" data-id=\"4d20d953\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a286bb4 elementor-widget elementor-widget-heading\" data-id=\"3a286bb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Description du projet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77f73239\" data-id=\"77f73239\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ce29d3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ce29d3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-708c7964\" data-id=\"708c7964\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d8f7aaf elementor-widget elementor-widget-text-editor\" data-id=\"5d8f7aaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\"><span style=\"font-size: 12.0pt; line-height: 107%;\">L&rsquo;h\u00f4pital universitaire de Tol\u00e8de, construit par l&rsquo;association commune des entreprises Acciona, OHL et Dragados, a une surface construite de 246 964 m<sup>2<\/sup> sur un terrain de 1 100 m\u00e8tres sur 300 m\u00e8tres. Il s&rsquo;agit d&rsquo;un b\u00e2timent fonctionnel, technologiquement avanc\u00e9, qui r\u00e9pond aux crit\u00e8res les plus exigeants en mati\u00e8re de durabilit\u00e9 et d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique.<\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"font-size: 12pt; color: var( --e-global-color-text );\">a conception architecturale int\u00e8gre de nombreux aspects qui, selon SESCAMont un \u00ab\u00a0impact direct sur la r\u00e9alisation d&rsquo;un environnement hospitalier humanis\u00e9\u00a0\u00bb. C&rsquo;est pourquoi, parmi plusieurs actions de diff\u00e9rentes natures, l&rsquo;importance de la r\u00e9duction et de l&rsquo;amortissement du bruit a \u00e9t\u00e9 soulign\u00e9e, le choix de nos portes acoustiques \u00e9tant l&rsquo;une des solutions adopt\u00e9es. Pour ce projet, nous avons d\u00e9cid\u00e9 de cr\u00e9er un test sp\u00e9cifique qui puisse r\u00e9pondre \u00e0 toutes les exigences de confort, de durabilit\u00e9 et de performance requises par un projet de ces caract\u00e9ristiques. C&rsquo;est ainsi qu&rsquo;est apparue sur le march\u00e9 notre porte acoustique 30 dB faite en polystyr\u00e8ne et un cadre en aluminium. ette porte a un coefficient d&rsquo;insonorisation suffisant pour pouvoir tenir des conversations en toute tranquillit\u00e9 \u00e0 l&rsquo;int\u00e9rieur des salles de consultation ou pour permettre le repos dans les chambres. De plus, le fait qu\u2019elle soit faite en polystyr\u00e8ne la rend tr\u00e8s maniable gr\u00e2ce \u00e0 son faible poids et le cadre en aluminium la rend r\u00e9sistante et \u00e9vite ainsi la d\u00e9gradation due \u00e0 l&rsquo;humidit\u00e9 et aux chocs des brancards ou des utilisateurs. La finition HPL apporte hygi\u00e8ne, robustesse et facilit\u00e9 d&rsquo;entretien et de conservation, tout en s&rsquo;harmonisant avec les grands espaces lumineux. En effet, les couleurs ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es selon les crit\u00e8res de la chromoth\u00e9rapie.<\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"color: var( --e-global-color-text ); font-size: 12pt;\">En tenant compte de ces caract\u00e9ristiques de configuration et de finition, nous compl\u00e9tons l&rsquo;ensemble avec des portes battantes et coulissantes, des portes modulaires sp\u00e9ciales \u00e0 trois vantaux pour permettre le passage le plus large possible, des portes adapt\u00e9es \u00e0 diff\u00e9rents \u00e9quipements pour leur automatisme et tous les types de portes plomb\u00e9es pour prot\u00e9ger les patients dans les salles de radiologie. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a689747 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a689747\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3172c175\" data-id=\"3172c175\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29e71b1 elementor-widget elementor-widget-spacer\" data-id=\"29e71b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":4775,"template":"","tipo_proyecto":[],"class_list":["post-5750","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor\" \/>\n<meta property=\"og:description\" content=\"H\u00f4pital universitaire de Toledo H\u00f4pital universitaire de Toledo L&rsquo;HUT compte plus de 5 000 portes fabriqu\u00e9es par Dayfor. Cet h\u00f4pital est le plus grand d&rsquo;Europe et le plus grand ouvrage civil de Castilla-La Mancha. Il se distingue par sa valeur architecturale et sa fonctionnalit\u00e9 en tant que centre hospitalier de grande capacit\u00e9. Localisation Toledo, Espagne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00e1brica de Puertas | Dayfor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GRUPODAYFOR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T16:56:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"651\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PuertasDayfor\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/\",\"url\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/\",\"name\":\"H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dayfor.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/portada.jpg\",\"datePublished\":\"2023-03-17T11:15:35+00:00\",\"dateModified\":\"2024-01-24T16:56:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dayfor.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/portada.jpg\",\"contentUrl\":\"https:\\\/\\\/dayfor.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/portada.jpg\",\"width\":651,\"height\":414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/hopital-universitaire-de-toledo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/proyecto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H\u00f4pital universitaire de Toledo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/\",\"name\":\"F\u00e1brica de Puertas | Dayfor\",\"description\":\"Puertas, Armarios, Molduras y Mamparas\",\"publisher\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#organization\",\"name\":\"F\u00e1brica de Puertas | Dayfor\",\"url\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dayfor.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-favicon-dayfor.png\",\"contentUrl\":\"https:\\\/\\\/dayfor.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-favicon-dayfor.png\",\"width\":512,\"height\":512,\"caption\":\"F\u00e1brica de Puertas | Dayfor\"},\"image\":{\"@id\":\"https:\\\/\\\/dayfor.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GRUPODAYFOR\",\"https:\\\/\\\/x.com\\\/PuertasDayfor\",\"https:\\\/\\\/www.instagram.com\\\/puertasdayfor\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/puertas-dayfor-s-l-\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor","og_description":"H\u00f4pital universitaire de Toledo H\u00f4pital universitaire de Toledo L&rsquo;HUT compte plus de 5 000 portes fabriqu\u00e9es par Dayfor. Cet h\u00f4pital est le plus grand d&rsquo;Europe et le plus grand ouvrage civil de Castilla-La Mancha. Il se distingue par sa valeur architecturale et sa fonctionnalit\u00e9 en tant que centre hospitalier de grande capacit\u00e9. Localisation Toledo, Espagne [&hellip;]","og_url":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/","og_site_name":"F\u00e1brica de Puertas | Dayfor","article_publisher":"https:\/\/www.facebook.com\/GRUPODAYFOR","article_modified_time":"2024-01-24T16:56:39+00:00","og_image":[{"width":651,"height":414,"url":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/portada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PuertasDayfor","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/","url":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/","name":"H\u00f4pital universitaire de Toledo - F\u00e1brica de Puertas | Dayfor","isPartOf":{"@id":"https:\/\/dayfor.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/#primaryimage"},"image":{"@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/#primaryimage"},"thumbnailUrl":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/portada.jpg","datePublished":"2023-03-17T11:15:35+00:00","dateModified":"2024-01-24T16:56:39+00:00","breadcrumb":{"@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/#primaryimage","url":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/portada.jpg","contentUrl":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/03\/portada.jpg","width":651,"height":414},{"@type":"BreadcrumbList","@id":"https:\/\/dayfor.com\/fr\/proyecto\/hopital-universitaire-de-toledo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dayfor.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/dayfor.com\/fr\/proyecto\/"},{"@type":"ListItem","position":3,"name":"H\u00f4pital universitaire de Toledo"}]},{"@type":"WebSite","@id":"https:\/\/dayfor.com\/fr\/#website","url":"https:\/\/dayfor.com\/fr\/","name":"F\u00e1brica de Puertas | Dayfor","description":"Puertas, Armarios, Molduras y Mamparas","publisher":{"@id":"https:\/\/dayfor.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dayfor.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dayfor.com\/fr\/#organization","name":"F\u00e1brica de Puertas | Dayfor","url":"https:\/\/dayfor.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dayfor.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/05\/cropped-favicon-dayfor.png","contentUrl":"https:\/\/dayfor.com\/wp-content\/uploads\/2023\/05\/cropped-favicon-dayfor.png","width":512,"height":512,"caption":"F\u00e1brica de Puertas | Dayfor"},"image":{"@id":"https:\/\/dayfor.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GRUPODAYFOR","https:\/\/x.com\/PuertasDayfor","https:\/\/www.instagram.com\/puertasdayfor\/","https:\/\/www.linkedin.com\/company\/puertas-dayfor-s-l-\/"]}]}},"_links":{"self":[{"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/proyecto\/5750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/types\/proyecto"}],"version-history":[{"count":1,"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/proyecto\/5750\/revisions"}],"predecessor-version":[{"id":5751,"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/proyecto\/5750\/revisions\/5751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/media\/4775"}],"wp:attachment":[{"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/media?parent=5750"}],"wp:term":[{"taxonomy":"tipo_proyecto","embeddable":true,"href":"https:\/\/dayfor.com\/fr\/wp-json\/wp\/v2\/tipo_proyecto?post=5750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}